{"id":2931,"date":"2024-12-11T11:50:11","date_gmt":"2024-12-11T10:50:11","guid":{"rendered":"https:\/\/olive-quail-903280.hostingersite.com\/szkolenia\/lecons-individuelles-de-polonais\/"},"modified":"2025-02-12T14:38:18","modified_gmt":"2025-02-12T13:38:18","slug":"lecons-individuelles-de-polonais","status":"publish","type":"szkolenia","link":"https:\/\/globalschool.pl\/fr\/szkolenia\/lecons-individuelles-de-polonais\/","title":{"rendered":"Le\u00e7ons individuelles de polonais"},"content":{"rendered":"\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-002093ebc41ed6db010e041f1dba8f92\"><br\/>O<strong>bjectif du cours<\/strong> Le cours individuel de polonais est adapt\u00e9 aux besoins, au niveau et aux objectifs du participant. L&rsquo;objectif des cours peut \u00eatre le suivant <\/p>\n\n<ul class=\"wp-block-list\">\n<li>l&rsquo;apprentissage d&rsquo;une langue \u00e0 partir de z\u00e9ro,<\/li>\n\n\n\n<li>l&rsquo;am\u00e9lioration des comp\u00e9tences en mati\u00e8re de communication,<\/li>\n\n\n\n<li>d\u00e9velopper le vocabulaire et la grammaire,<\/li>\n\n\n\n<li>la pr\u00e9paration aux examens linguistiques,<\/li>\n\n\n\n<li>le d\u00e9veloppement de comp\u00e9tences linguistiques dans un domaine sp\u00e9cifique (par exemple, les affaires, la m\u00e9decine, le droit).<\/li>\n<\/ul>\n\n<p><strong>Pour qui ?<\/strong><br\/>Le cours est con\u00e7u pour :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>les \u00e9trangers souhaitant apprendre la langue polonaise,<\/li>\n\n\n\n<li>les personnes qui se pr\u00e9parent \u00e0 vivre, travailler ou \u00e9tudier en Pologne,<\/li>\n\n\n\n<li>toute personne souhaitant am\u00e9liorer ses comp\u00e9tences linguistiques \u00e0 un rythme individuel.<\/li>\n<\/ul>\n\n<p><br\/>F<strong>ormat du<\/strong> cours Les cours sont dispens\u00e9s sur une base individuelle, ce qui permet une adaptation compl\u00e8te aux besoins du participant. Possible : <\/p>\n\n<ul class=\"wp-block-list\">\n<li>les cours r\u00e9sidentiels,<\/li>\n\n\n\n<li>des cours en ligne,<\/li>\n\n\n\n<li>des r\u00e9unions hybrides.<\/li>\n<\/ul>\n\n<p><br\/>P<strong>rogramme de cours<\/strong> Le programme de cours est flexible et adapt\u00e9 :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>niveau de langue (A1-C2),<\/li>\n\n\n\n<li>les objectifs du participant,<\/li>\n\n\n\n<li>et des exigences professionnelles ou personnelles sp\u00e9cifiques.<\/li>\n<\/ul>\n\n<p>Exemples de domaines d&rsquo;apprentissage :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>les bases de la communication en polonais,<\/li>\n\n\n\n<li>l&rsquo;\u00e9criture et la lecture de textes,<\/li>\n\n\n\n<li>une prononciation et un accent corrects,<\/li>\n\n\n\n<li>la grammaire et la structure de la langue,<\/li>\n\n\n\n<li>vocabulaire th\u00e9matique sp\u00e9cifique.<\/li>\n<\/ul>\n\n<p><br\/>M<strong>at\u00e9riel d&rsquo;<\/strong>apprentissage Nous donnons acc\u00e8s \u00e0 une vari\u00e9t\u00e9 de mat\u00e9riel d&rsquo;apprentissage tel que<\/p>\n\n<ul class=\"wp-block-list\">\n<li>les manuels scolaires,<\/li>\n\n\n\n<li>des exercices interactifs,<\/li>\n\n\n\n<li>du mat\u00e9riel multim\u00e9dia,<\/li>\n\n\n\n<li>des textes authentiques.<\/li>\n<\/ul>\n\n<p><strong>Dur\u00e9e et fr\u00e9quence des cours<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>L&rsquo;horaire des cours est \u00e9tabli sur une base individuelle.<\/li>\n\n\n\n<li>Les cours peuvent avoir lieu plusieurs fois par semaine ou de mani\u00e8re intensive.<\/li>\n<\/ul>\n\n<p><strong>Avantages<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Apprendre \u00e0 son rythme.<\/li>\n\n\n\n<li>L&rsquo;attention du lecteur est totale.<\/li>\n\n\n\n<li>Capacit\u00e9 \u00e0 progresser rapidement.<\/li>\n\n\n\n<li>D\u00e9veloppement de comp\u00e9tences pratiques en mati\u00e8re de communication.<\/li>\n<\/ul>\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-b4479985c055fdc0b7b0f66bbc271a47\">N&rsquo;h\u00e9sitez pas \u00e0 nous contacter pour obtenir des d\u00e9tails sur les cours et pour adapter une offre \u00e0 vos besoins !<\/p>\n\n<p><\/p>\n","protected":false},"featured_media":2932,"template":"","formulaszkolenia":[706],"jezyk":[715],"poziom":[733],"rodzaj":[],"specjalizacja":[],"tryb":[767],"typ":[770],"zajecia":[779],"class_list":["post-2931","szkolenia","type-szkolenia","status-publish","has-post-thumbnail","hentry","formulaszkolenia-fast-fr","jezyk-polski-fr","poziom-a2-troche-rozumiem-fr","tryb-online-fr","typ-konwersacje-fr","zajecia-indywidualne-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/szkolenia\/2931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/szkolenia"}],"about":[{"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/types\/szkolenia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/media\/2932"}],"wp:attachment":[{"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/media?parent=2931"}],"wp:term":[{"taxonomy":"formulaszkolenia","embeddable":true,"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/formulaszkolenia?post=2931"},{"taxonomy":"jezyk","embeddable":true,"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/jezyk?post=2931"},{"taxonomy":"poziom","embeddable":true,"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/poziom?post=2931"},{"taxonomy":"rodzaj","embeddable":true,"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/rodzaj?post=2931"},{"taxonomy":"specjalizacja","embeddable":true,"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/specjalizacja?post=2931"},{"taxonomy":"tryb","embeddable":true,"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/tryb?post=2931"},{"taxonomy":"typ","embeddable":true,"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/typ?post=2931"},{"taxonomy":"zajecia","embeddable":true,"href":"https:\/\/globalschool.pl\/fr\/wp-json\/wp\/v2\/zajecia?post=2931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}