{"id":2933,"date":"2024-12-11T11:50:11","date_gmt":"2024-12-11T10:50:11","guid":{"rendered":"https:\/\/olive-quail-903280.hostingersite.com\/szkolenia\/einzelunterricht-polnisch\/"},"modified":"2025-02-12T14:38:18","modified_gmt":"2025-02-12T13:38:18","slug":"einzelunterricht-polnisch","status":"publish","type":"szkolenia","link":"https:\/\/globalschool.pl\/de\/szkolenia\/einzelunterricht-polnisch\/","title":{"rendered":"Einzelunterricht Polnisch"},"content":{"rendered":"\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-96ce516c3550305a395dd083ec0b9592\"><br\/>Z<strong>iel des Kurses<\/strong> Der individuelle Polnisch-Sprachkurs wird auf die Bed\u00fcrfnisse, das Niveau und die Ziele des Teilnehmers zugeschnitten. Das Ziel des Unterrichts kann sein: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>eine Sprache von Grund auf zu lernen,<\/li>\n\n\n\n<li>Verbesserung der Kommunikationsf\u00e4higkeiten,<\/li>\n\n\n\n<li>Wortschatz und Grammatik zu entwickeln,<\/li>\n\n\n\n<li>Vorbereitung auf Sprachpr\u00fcfungen,<\/li>\n\n\n\n<li>Entwicklung von Sprachkenntnissen in einem bestimmten Bereich (z. B. Wirtschaft, Medizin, Recht).<\/li>\n<\/ul>\n\n<p><strong>F\u00fcr wen?<\/strong><br\/>Der Kurs ist konzipiert f\u00fcr:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Ausl\u00e4nder, die die polnische Sprache lernen m\u00f6chten,<\/li>\n\n\n\n<li>Menschen, die sich darauf vorbereiten, in Polen zu leben, zu arbeiten oder zu studieren,<\/li>\n\n\n\n<li>alle, die ihre Sprachkenntnisse in einem individuellen Tempo verbessern m\u00f6chten.<\/li>\n<\/ul>\n\n<p><br\/>U<strong>nterrichtsformat<\/strong> Der Unterricht wird als Einzelunterricht abgehalten, so dass er ganz auf die Bed\u00fcrfnisse des Teilnehmers zugeschnitten werden kann. M\u00f6glich: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Unterricht zu Hause,<\/li>\n\n\n\n<li>Online-Kurse,<\/li>\n\n\n\n<li>Hybridtreffen.<\/li>\n<\/ul>\n\n<p><br\/>K<strong>ursprogramm<\/strong> Das Kursprogramm ist flexibel und angepasst an:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sprachniveau (A1-C2),<\/li>\n\n\n\n<li>Ziele der Teilnehmer,<\/li>\n\n\n\n<li>Interessen und besonderen beruflichen oder pers\u00f6nlichen Anforderungen.<\/li>\n<\/ul>\n\n<p>Beispiele f\u00fcr Lernbereiche:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Grundlagen der Kommunikation auf Polnisch,<\/li>\n\n\n\n<li>Texte schreiben und lesen,<\/li>\n\n\n\n<li>korrekte Aussprache und Akzent,<\/li>\n\n\n\n<li>Grammatik und Sprachstruktur,<\/li>\n\n\n\n<li>spezifisches thematisches Vokabular.<\/li>\n<\/ul>\n\n<p><br\/>L<strong>ernmaterialien<\/strong> Wir bieten Zugang zu einer Vielzahl von Lernmaterialien wie z.B.:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Lehrb\u00fccher,<\/li>\n\n\n\n<li>interaktive \u00dcbungen,<\/li>\n\n\n\n<li>Multimedia-Materialien,<\/li>\n\n\n\n<li>authentische Texte.<\/li>\n<\/ul>\n\n<p><strong>Dauer und H\u00e4ufigkeit des Unterrichts<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Der Kursplan wird auf individueller Basis festgelegt.<\/li>\n\n\n\n<li>Der Unterricht kann mehrmals pro Woche oder als Intensivkurs stattfinden.<\/li>\n<\/ul>\n\n<p><strong>Vorteile<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Lernen in einem angenehmen Tempo.<\/li>\n\n\n\n<li>Volle Aufmerksamkeit des Lesers.<\/li>\n\n\n\n<li>Die F\u00e4higkeit, schnelle Fortschritte zu machen.<\/li>\n\n\n\n<li>Entwicklung von praktischen Kommunikationsf\u00e4higkeiten.<\/li>\n<\/ul>\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-b809023f0628f2d57d4928b70fb3753a\">Bitte kontaktieren Sie uns f\u00fcr weitere Informationen zu den Kursen und um ein auf Ihre Bed\u00fcrfnisse zugeschnittenes Angebot zu erhalten!<\/p>\n\n<p><\/p>\n","protected":false},"featured_media":3305,"template":"","formulaszkolenia":[707],"jezyk":[716],"poziom":[735],"rodzaj":[],"specjalizacja":[],"tryb":[768],"typ":[772],"zajecia":[780],"class_list":["post-2933","szkolenia","type-szkolenia","status-publish","has-post-thumbnail","hentry","formulaszkolenia-fast-de","jezyk-polski-de","poziom-a2-troche-rozumiem-de","tryb-online-de","typ-konwersacje-de","zajecia-indywidualne-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/szkolenia\/2933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/szkolenia"}],"about":[{"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/types\/szkolenia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/media\/3305"}],"wp:attachment":[{"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/media?parent=2933"}],"wp:term":[{"taxonomy":"formulaszkolenia","embeddable":true,"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/formulaszkolenia?post=2933"},{"taxonomy":"jezyk","embeddable":true,"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/jezyk?post=2933"},{"taxonomy":"poziom","embeddable":true,"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/poziom?post=2933"},{"taxonomy":"rodzaj","embeddable":true,"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/rodzaj?post=2933"},{"taxonomy":"specjalizacja","embeddable":true,"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/specjalizacja?post=2933"},{"taxonomy":"tryb","embeddable":true,"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/tryb?post=2933"},{"taxonomy":"typ","embeddable":true,"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/typ?post=2933"},{"taxonomy":"zajecia","embeddable":true,"href":"https:\/\/globalschool.pl\/de\/wp-json\/wp\/v2\/zajecia?post=2933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}